{"id":3710,"date":"2011-08-27T12:35:30","date_gmt":"2011-08-27T10:35:30","guid":{"rendered":"http:\/\/rsv-barntrup.de\/Wordpress\/?p=3710"},"modified":"2011-08-27T12:39:42","modified_gmt":"2011-08-27T10:39:42","slug":"achterbahnfahrt-der-gefuhle","status":"publish","type":"post","link":"https:\/\/rsv-barntrup.de\/Wordpress\/news\/achterbahnfahrt-der-gefuhle\/","title":{"rendered":"Achterbahnfahrt der Gef\u00fchle"},"content":{"rendered":"<p>So unsicher und unbest\u00e4ndig wie das Wetter zeigte sich das Spiel des RSV gegen die Reserve des SC Verl. Nach der Klatsche gegen Clarholz zeigte sich RSV von Beginn an deutlich verbessert. Der RSV suchte sein Heil in der Offensive und setzte nicht auf die fehlgeschlagene Mauertaktik. Die Gegenspieler wurden fr\u00fch attackiert und gut gedoppelt. Bereits in der Anfangsphase hatten die Rot-Schwarzen zwei gute Torchancen, die jedoch noch nicht zum gew\u00fcnschten Erfolg f\u00fchrten. So kam es wie es kommen musste. Verl, das bis dato noch nicht einen vern\u00fcnftigen Angriff vorgetragen hatte, ging nach einem Abstimmungsfehler in der RSV-Defensive in der 17. Minute in F\u00fchrung. Die F\u00fchrung f\u00fcr die Verler w\u00e4hrte aber nicht lange. Bereits 5 Minuten sp\u00e4ter konnte der RSV aus der optimischen \u00dcberlegenheit Profit schlagen. Nach einem abgeblockten Freisto\u00df kam Hagemann aus 20 Metern an den Ball. Sein Schuss schlug (zum Gl\u00fcck) fehl und landete beim v\u00f6llig freistehenden Daniel Schlingmann, der den Ball samt Keeper \u00fcber die Linie wuchtete. Nach noch nicht einmal einer halben Stunde erzielte der RSV einen weiteren Treffer und ging mit 2-1 in F\u00fchrung. Sch\u00f6nfelder legte den Ball auf der halbrechten Seite auf Rethmeier ab, der von der Strafraumkante trocken vollendete.<br \/>\nNach der F\u00fchrung verlie\u00df den RSV der Mut. Verl wurde st\u00e4rker und dr\u00e4ngte auf den Ausgleich. Barntrup zog sich in die eigene H\u00e4lfte zur\u00fcck und \u00fcberlie\u00df Verl die Spielgestaltung. Bis zur Pause ergaben sich jedoch keine Chancen f\u00fcr den Gast, sodass sich der RSV mit einer 2-1 F\u00fchrung in die Pause verabschiedete.<\/p>\n<p>Nach dem Seitenwechsel wurde das Spiel k\u00f6rperbetonter und deutlich intensiver. Ein Revanchefoul an &#8218;Paule&#8216; Funk sahen weder der Schiedsrichter noch seine beiden Assistenten. Nach knapp einer Stunde wurden die Verler Angriffsversuche belohnt. Ein Distanzschuss schlug unhaltbar f\u00fcr den gerade aus den Flitterwochen zur\u00fcckgekehrten Felde im Geh\u00e4use ein. Die Barntruper Defensive hatte dem Torsch\u00fctzen auf seinem Weg durch die eigene H\u00e4lfte lediglich brav Geleitschutz gegeben. Eine Viertelstunde vor Schluss dann der Schock f\u00fcr alle RSV-Fans. Ein Freisto\u00df der Verler von der Strafraumkante schlug zum Entsetzen aller im RSV-Tor ein. Nach einer 2-1 F\u00fchrung lag der RSV nun mit 2-3 zur\u00fcck und niemand wusste warum???<br \/>\nWer dachte, dass sich der RSV in sein Schicksal ergab, der irrte sich gewaltig. Bereits f\u00fcnf Minuten sp\u00e4ter konnte das Kopfballungeheuer Sch\u00f6nfelder nach einem Hagemann-Freisto\u00df den erneuten Ausgleich erzielen. Dieses gab dem RSV neuen Schwung f\u00fcr die Schlussphase, in der sich die Ereignisse \u00fcberschlugen. Der eingewechselte Altrogge lief zun\u00e4chst gemeinsam mit Hagemann allein auf den Verler Keeper zu. Anstatt den v\u00f6llig blanken Hagemann anzuspielen, der das Leder nur \u00fcber die Linie dr\u00fccken musste, entschied sich der Schwatte, sein Gl\u00fcck selbst zu versuchen. Der Keeper parierte zur Ecke. Wer eine m\u00f6gliche F\u00fchrung zu leichtfertig und egoistisch vergibt, darf doch nicht belohnt werden. DOCH, er darf. Bei der anschlie\u00dfenden Ecke war es ausgerechnet Altrogge, der den Ball am langen Pfosten in den Verler Kasten k\u00f6pfte. Grenzenloser Jubel machte sich breit.<br \/>\nNach schier endloser Nachspielzeit hatte der RSV die ersten 3 Punkte in der neuen Saison auf dem Konto. Am n\u00e4chsten Wochenende steht f\u00fcr den RSV das Lippe-Derby gegen den SC Bad Salzuflen auf dem Programm. Auch hier m\u00f6chte der RSV eine gute Rolle spielen und vielleicht einen Punkt aus der Kurstadt entf\u00fchren.<\/p>\n<p><span style=\"text-decoration: underline\"><strong>Aufstellung RSV:<\/strong><\/span><br \/>\nFelde (C) &#8211; Kryker (Neide) &#8211; D. Schlingmann &#8211; Maule &#8211; Meier &#8211; Funk &#8211; S\u00f6lter &#8211; Schalofsky &#8211; Hagemann &#8211; Sch\u00f6nfelder &#8211; Rethmeier (Altrogge)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>So unsicher und unbest\u00e4ndig wie das Wetter zeigte sich das Spiel des RSV gegen die Reserve des SC Verl. Nach der Klatsche gegen Clarholz zeigte sich RSV von Beginn an deutlich verbessert. Der RSV suchte sein Heil in der Offensive und setzte nicht auf die fehlgeschlagene Mauertaktik. Die Gegenspieler wurden fr\u00fch attackiert und gut gedoppelt. Bereits in der Anfangsphase hatten die Rot-Schwarzen zwei gute Torchancen, die jedoch noch nicht zum gew\u00fcnschten Erfolg f\u00fchrten. So kam es wie es kommen musste. Verl, das bis dato noch nicht einen vern\u00fcnftigen Angriff vorgetragen hatte, ging nach einem Abstimmungsfehler in der RSV-Defensive in der 17. Minute in F\u00fchrung. Die F\u00fchrung f\u00fcr die Verler w\u00e4hrte aber nicht lange. Bereits 5 Minuten sp\u00e4ter konnte der RSV aus der optimischen \u00dcberlegenheit Profit schlagen. Nach einem abgeblockten Freisto\u00df kam Hagemann aus 20 Metern an den Ball. Sein Schuss schlug (zum Gl\u00fcck) fehl und landete beim v\u00f6llig freistehenden Daniel Schlingmann, der den Ball samt Keeper \u00fcber die Linie wuchtete. Nach noch nicht einmal einer halben Stunde erzielte der RSV einen weiteren Treffer und ging mit 2-1 in F\u00fchrung. Sch\u00f6nfelder legte den Ball auf der halbrechten Seite auf Rethmeier ab, der von der Strafraumkante trocken vollendete. Nach der F\u00fchrung verlie\u00df den RSV der Mut. Verl wurde st\u00e4rker und dr\u00e4ngte auf den Ausgleich. Barntrup zog sich in die eigene H\u00e4lfte zur\u00fcck und \u00fcberlie\u00df Verl die Spielgestaltung. Bis zur Pause ergaben sich jedoch keine Chancen f\u00fcr den Gast, sodass sich der RSV mit einer 2-1 F\u00fchrung in die Pause verabschiedete. Nach dem Seitenwechsel wurde das Spiel k\u00f6rperbetonter und deutlich intensiver. Ein Revanchefoul an &#8218;Paule&#8216; Funk sahen weder der Schiedsrichter noch seine beiden Assistenten. Nach knapp einer Stunde wurden die Verler Angriffsversuche belohnt. Ein Distanzschuss schlug unhaltbar f\u00fcr den gerade aus den Flitterwochen zur\u00fcckgekehrten Felde im Geh\u00e4use ein. Die Barntruper Defensive hatte dem Torsch\u00fctzen auf seinem Weg durch die eigene H\u00e4lfte lediglich brav Geleitschutz gegeben. Eine Viertelstunde vor Schluss dann der Schock f\u00fcr alle RSV-Fans. Ein Freisto\u00df der Verler von der Strafraumkante schlug zum Entsetzen aller im RSV-Tor ein. Nach einer 2-1 F\u00fchrung lag der RSV nun mit 2-3 zur\u00fcck und niemand wusste warum??? Wer dachte, dass sich der RSV in sein Schicksal ergab, der irrte sich gewaltig. Bereits f\u00fcnf Minuten sp\u00e4ter konnte das Kopfballungeheuer Sch\u00f6nfelder nach einem Hagemann-Freisto\u00df den erneuten Ausgleich erzielen. Dieses gab dem RSV neuen Schwung f\u00fcr die Schlussphase, in der sich die Ereignisse \u00fcberschlugen. Der eingewechselte Altrogge lief zun\u00e4chst gemeinsam mit Hagemann allein auf den Verler Keeper zu. Anstatt den v\u00f6llig blanken Hagemann anzuspielen, der das Leder nur \u00fcber die Linie dr\u00fccken musste, entschied sich der Schwatte, sein Gl\u00fcck selbst zu versuchen. Der Keeper parierte zur Ecke. Wer eine m\u00f6gliche F\u00fchrung zu leichtfertig und egoistisch vergibt, darf doch nicht belohnt werden. DOCH, er darf. Bei der anschlie\u00dfenden Ecke war es ausgerechnet Altrogge, der den Ball am langen Pfosten in den Verler Kasten k\u00f6pfte. Grenzenloser Jubel machte sich breit. Nach schier endloser Nachspielzeit hatte der RSV die ersten 3 Punkte in der neuen Saison auf dem Konto. Am n\u00e4chsten Wochenende steht f\u00fcr den RSV das Lippe-Derby gegen den SC Bad Salzuflen auf dem Programm. Auch hier m\u00f6chte der RSV eine gute Rolle spielen und vielleicht einen Punkt aus der Kurstadt entf\u00fchren. Aufstellung RSV: Felde (C) &#8211; Kryker (Neide) &#8211; D. Schlingmann &#8211; Maule &#8211; Meier &#8211; Funk &#8211; S\u00f6lter &#8211; Schalofsky &#8211; Hagemann &#8211; Sch\u00f6nfelder &#8211; Rethmeier (Altrogge)<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[3,1],"tags":[],"class_list":["post-3710","post","type-post","status-publish","format-standard","hentry","category-1-herren","category-news"],"blocksy_meta":[],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6yR9L-XQ","publishpress_future_action":{"enabled":false,"date":"2026-07-22 13:00:15","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/3710","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/comments?post=3710"}],"version-history":[{"count":4,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/3710\/revisions"}],"predecessor-version":[{"id":3760,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/3710\/revisions\/3760"}],"wp:attachment":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/media?parent=3710"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/categories?post=3710"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/tags?post=3710"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}