{"id":400,"date":"2010-09-17T19:06:45","date_gmt":"2010-09-17T17:06:45","guid":{"rendered":"http:\/\/rsv-barntrup.de\/Wordpress\/?p=400"},"modified":"2010-09-18T04:27:57","modified_gmt":"2010-09-18T02:27:57","slug":"es-lauft-und-lauft-und-lauft%e2%80%a6","status":"publish","type":"post","link":"https:\/\/rsv-barntrup.de\/Wordpress\/herren\/2-herren\/es-lauft-und-lauft-und-lauft%e2%80%a6\/","title":{"rendered":"Es l\u00e4uft und l\u00e4uft und l\u00e4uft\u2026.."},"content":{"rendered":"<p><strong>Kreisliga B (Gruppe 1)<\/strong><\/p>\n<p><strong>8. Spieltag <\/strong><\/p>\n<h2><span style=\"color: #ff0000;\"><strong>RSV Barntrup II &#8211; TSV Kirchheide 4:0<\/strong><\/span><\/h2>\n<p>Am gestrigen Donnerstag war einer der vermeidlichen Aufstiegskandidaten im Waldstadion zu Gast. Der TSV Kirchheide konnte allerdings in dieser Saison bisher noch nicht den Vorschusslorbeeren gerecht werden. Selbst gg. die eigene Zwote konnte kein 3er eingefahren werden. Dennoch warnte Coach Motzkuhn davor den Gegner zu untersch\u00e4tzen, denn dieser habe heute seine letzte Chance um Anschluss zu halten. Kurzfristig musste der RSV auf Weber und K\u00f6ller verzichten, letztere erlitt einen Muskelb\u00fcndelriss und wird voraussichtlich in der Hinserie ausfallen. Das Team w\u00fcnscht Ihm alles Gute und eine schnelle Genesung.<\/p>\n<p>Die erste Halbzeit begann verhalten. Der RSV erwischte zwar den besseren Start, doch wie schon in Entrup konnten die fr\u00fchen Chancen nicht verwertet werden. Johnson, D.Philipps und C. Philipps scheiterten aus aussichtsreicher Position am gut aufgelegten G\u00e4stekeeper. Nach den ersten 15 min. verflachte die Partie und der TSV wurde st\u00e4rker. Der RSV tat in dieser Phase zu wenig, man stand zu weit von den M\u00e4nnern, Angriffe wurden kl\u00e4glich abgeschlossen und der Spielfluss war einfach nicht zu erkennen. Trotzdem konnte der TSV aus dieser Phase kein Kapital schlagen. Angriffe endeten sp\u00e4testens am 16er und Torwart Sievert war fast arbeitslos. Zum Ende der ersten Halbzeit wurde dann der Kampf besser angenommen und er RSV attackierte den Gegner fr\u00fcher. Trotzdem muss man sagen, dass dies eine Halbzeit der schlechteren Sorte gewesen ist.<\/p>\n<p>Coach Motzkun r\u00fcttelte die Mannschaft mit einer beherzten Rede das Team in der Halbzeitpause auf, au\u00dferdem wurde die Offensive umgestellt, um im Mittelfeld die R\u00e4ume enger zu gestalten.<\/p>\n<p>Die Rede hatte gefruchtet, denn sofort nach Wiederanpfiff war der RSV hellwach und auf der H\u00f6he. Nach einer Balleroberung im Mittelfeld ging es in der 47 Minute ganz schnell \u00fcber Reese und C. Phlipps gelang der Ball zu D. Phlipps und dieser nutzte seine Chance eiskalt. Durch das fr\u00fche Tor war der TSV sichtlich geschockt und der RSV machte weiter Gas. Angriffe des TSV endeten reihenweise im Mittelfeld, welches kompakt und sicher stand. In der 55. Spielminute tankte sich Johnson durch und wurde mit unfairen Mitteln im 16er gestoppt, der Pfiff des unparteiischen blieb allerdings, wie sooft in dieser Partie, aus. Nach Hereingabe durch Reese konnte Kryker aus dem Gew\u00fchl zum 2:0 einnetzen. Schon jetzt war zu sp\u00fcren, dass dieses Ergebnis und die 3 Punkte nicht mehr aus der Hand gegeben w\u00fcrden. In der 65 Minute dann eine Schocksekunde f\u00fcr den RSV. In einem Kopfballduell prallte D. Phlipps erst mit dem Gegner und dann volle Wucht mit der heiligen roten Erde zusammen. Kr\u00fcmmend vor Schmerzen musste dieser erst auf dem Feld und dann in der Kabine behandelt werden. Der TSV wurde in der Folgezeit ein ums andere Mal \u00fcberlaufen und das Ergebnis h\u00e4tte schon viel fr\u00fcher aufgestockt werden k\u00f6nnen. Die RSV Akteure scheiterten allerdings entweder am guten Keeper oder an der eigenen \u00dcbersicht und Ruhe. In der 83. min konnten die RSV Anh\u00e4nger dann wieder Jubeln, nach einer tollen Kombination tankte sich \u201eUns Sticken\u201c D\u00fcmpe durch die Abwehrreihen und markierte sicher und l\u00e4ssig das 3:0. Der TSV war geschlagen. In den letzten 10 min. wurde das Ergebnis verwaltet. M. Reese kr\u00f6nte seine Leistung in der 90. min. mit seinem Treffer zu, 4:0 Endstand.<\/p>\n<p>Fazit:<\/p>\n<p>Nach toller 2ten Halbzeit ein, auch in dieser H\u00f6he, verdienter Sieg. Der RSV marschiert weiter. Das Jahr 2010 ist das beste Jahr in der Geschichte der Zweiten. Es freut uns, dass mehr und mehr Zuschauer uns auch zu Ausw\u00e4rtsspielen begleiten.<\/p>\n<p>Am Wochenende kommt es dann zum Showdown im Kalletal, hier hei\u00dft es volle Konzentration und Kampf von der ersten Minute an. Sollte hier ein weiterer Dreier gelingen, k\u00f6nnte man sich erstmals von der Konkurrenz absetzen.<\/p>\n<p>Aufstellung: Sievert\/Rausch\/Betke\/D\u00fcmpe\/Dubbert (81. Schn\u00fcll)\/Kryker\/Reese\/Schlingmann S.\/ C. Phlipps, Johnson. D. Phlipps (65. Siemens)<\/p>\n<p>Tore: D. Philipps (47), Kryker (60), D\u00fcmpe (83), Reese (90)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Am gestrigen Donnerstag war einer der vermeidlichen Aufstiegskandidaten im Waldstadion zu Gast.<\/p>\n","protected":false},"author":10,"featured_media":409,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,20],"tags":[],"class_list":["post-400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-2-herren","category-herren"],"blocksy_meta":[],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/rsv-barntrup.de\/Wordpress\/wp-content\/uploads\/2010\/09\/Senioren2.png?fit=182%2C171&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6yR9L-6s","publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:02:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/comments?post=400"}],"version-history":[{"count":6,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/400\/revisions"}],"predecessor-version":[{"id":413,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/400\/revisions\/413"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/media\/409"}],"wp:attachment":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/media?parent=400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/categories?post=400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/tags?post=400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}