{"id":5022,"date":"2012-05-08T20:35:49","date_gmt":"2012-05-08T18:35:49","guid":{"rendered":"http:\/\/rsv-barntrup.de\/Wordpress\/?p=5022"},"modified":"2012-05-08T22:27:26","modified_gmt":"2012-05-08T20:27:26","slug":"231-tore-in-3-spielen-torhungriger-rsvii","status":"publish","type":"post","link":"https:\/\/rsv-barntrup.de\/Wordpress\/news\/231-tore-in-3-spielen-torhungriger-rsvii\/","title":{"rendered":"23:1 Tore in 3 Spielen&#8230;.Torhungriger RSVII"},"content":{"rendered":"<p>Nach den traurigen letzten 2 Wochen ging es f\u00fcr den RSVII gegen die Reserve des TBV Lemgos ran. Vor Spielbeginn \u00fcberreichten die Spieler des TBV einen Rosenstrau\u00df und dr\u00fcckten Ihr Beilid aus. Eine tolle Geste der gesamten Mannschaft, was allerdings\u00a0 die Spieler des RSV sofort wieder an die Bilder und Gedanken der letzten Wochen erinnerte.<\/p>\n<p>Zum Spiel kann man eigentlich nicht sehr viel sagen, der RSV spielte in den ersten 10 Minuten noch mit Respekt, legte diesen allerdings relativ schnell ab und erspielte sich eine nach der anderen M\u00f6glichkeit. Leider hatten unser St\u00fcrmer Hoffmann und C. Philipps nicht ihre besten Tag erwischt und so mussten die Mannen von Trainer R. Motzkuhn bis zur 32 Minute warten, bis N. Weber, nach einer Klasse hereingabe von C. Philipps, die Kugel versenken konnte. Doch auch nach der F\u00fchrung wollte kein zweiter Treffer gelingen, obwohl man nur auf ein Tor st\u00fcrmte und so ging es, mit einer nicht\u00a0 ganz so komfortablen F\u00fchrung in die Pause, \u00e4hnlich wie im Spiel gegen L\u00fcrdissen.<\/p>\n<p>R. Motzkuhn warnte seine Spieler, nicht leichtsinnig die zweite Halbzeit anzugehen, sondern dort anzukn\u00fcpfen, wo man aufgeh\u00f6rt hatte. Leider konnte das Team diese Vorgabe in den ersten 10 minuten nach dem Wechsel nicht umsetzen und der TBV kam besser ins Spiel und seinerseits zu Chancen. Doch E. Kryker versetzte den Angriffsbem\u00fchungen des TBV mit seinem Treffer zum 2:0 ein Ende. Nach dem Treffer reagierte Trainerfuchs Motzkuhn und brachten mit D. Philipps und M. L\u00fcbeck gleich zwei neue St\u00fcrmer. D. Philipps setzte sich gleich in Szene und legte S. Schlingmann das 3:0 auf. Der Drops war mit diesem Treffer gelutscht und wie schon beim 10:1 gg. L\u00fcrdissen beherrschte der RSV den Gegner ab diesem Zeitpunk nach Belieben. Beim 4:0 durfte D. Philipps dann selbst jubeln, ehe er wieder, am 5:0 durch L. Schmidt, beteiligt war. L. Schmidt hatte kurz zuvor einen Foulelfmeter, nach Foul an Weber, Richtung Parkpalette gesetzt und machte mit seinem Treffer diesen Fehlschuss wieder gut. Zwischendurch h\u00e4tte M. Rausch das Ergebnis noch aufstocken k\u00f6nnen, doch dieser traf gleich 2x ungl\u00fccklich Aluminium. Das 6:0 besorgte dann wiederum Schlingman, nachdem ein Lemgoer Spieler gleich 3x den eigenen Torwart anschoss&#8230; ein kurioses Ding, was den Einen oder Anderen etwas schmunzeln lie\u00df . Nach dem 7:0 durch L\u00fcbeck, kr\u00f6nte N. Weber seine Leistung am heutigen Tag mit dem 8:0&#8230;..<\/p>\n<p>Fazit:<\/p>\n<p>Die Mannschaft zeigt derzeit vor allem in der zweiten Halbzeit \u00fcberraschende Fitness und &#8222;Torgeilheit&#8220;. Nachdem die R\u00fcckserie erst schleppend begonnen hat, scheint sich das Team nun gefunden zu haben und es macht Spa\u00df zu sehen, dass man trotz einer komfortablen F\u00fchrung nicht aufh\u00f6rt zu fighten.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nach den traurigen letzten 2 Wochen ging es f\u00fcr den RSVII gegen die Reserve des TBV Lemgos ran. Vor Spielbeginn \u00fcberreichten die Spieler des TBV einen Rosenstrau\u00df und dr\u00fcckten Ihr Beilid aus. Eine tolle Geste der gesamten Mannschaft, was allerdings\u00a0 die Spieler des RSV sofort wieder an die Bilder und Gedanken der letzten Wochen erinnerte. Zum Spiel kann man eigentlich nicht sehr viel sagen, der RSV spielte in den ersten 10 Minuten noch mit Respekt, legte diesen allerdings relativ schnell ab und erspielte sich eine nach der anderen M\u00f6glichkeit. Leider hatten unser St\u00fcrmer Hoffmann und C. Philipps nicht ihre besten Tag erwischt und so mussten die Mannen von Trainer R. Motzkuhn bis zur 32 Minute warten, bis N. Weber, nach einer Klasse hereingabe von C. Philipps, die Kugel versenken konnte. Doch auch nach der F\u00fchrung wollte kein zweiter Treffer gelingen, obwohl man nur auf ein Tor st\u00fcrmte und so ging es, mit einer nicht\u00a0 ganz so komfortablen F\u00fchrung in die Pause, \u00e4hnlich wie im Spiel gegen L\u00fcrdissen. R. Motzkuhn warnte seine Spieler, nicht leichtsinnig die zweite Halbzeit anzugehen, sondern dort anzukn\u00fcpfen, wo man aufgeh\u00f6rt hatte. Leider konnte das Team diese Vorgabe in den ersten 10 minuten nach dem Wechsel nicht umsetzen und der TBV kam besser ins Spiel und seinerseits zu Chancen. Doch E. Kryker versetzte den Angriffsbem\u00fchungen des TBV mit seinem Treffer zum 2:0 ein Ende. Nach dem Treffer reagierte Trainerfuchs Motzkuhn und brachten mit D. Philipps und M. L\u00fcbeck gleich zwei neue St\u00fcrmer. D. Philipps setzte sich gleich in Szene und legte S. Schlingmann das 3:0 auf. Der Drops war mit diesem Treffer gelutscht und wie schon beim 10:1 gg. L\u00fcrdissen beherrschte der RSV den Gegner ab diesem Zeitpunk nach Belieben. Beim 4:0 durfte D. Philipps dann selbst jubeln, ehe er wieder, am 5:0 durch L. Schmidt, beteiligt war. L. Schmidt hatte kurz zuvor einen Foulelfmeter, nach Foul an Weber, Richtung Parkpalette gesetzt und machte mit seinem Treffer diesen Fehlschuss wieder gut. Zwischendurch h\u00e4tte M. Rausch das Ergebnis noch aufstocken k\u00f6nnen, doch dieser traf gleich 2x ungl\u00fccklich Aluminium. Das 6:0 besorgte dann wiederum Schlingman, nachdem ein Lemgoer Spieler gleich 3x den eigenen Torwart anschoss&#8230; ein kurioses Ding, was den Einen oder Anderen etwas schmunzeln lie\u00df . Nach dem 7:0 durch L\u00fcbeck, kr\u00f6nte N. Weber seine Leistung am heutigen Tag mit dem 8:0&#8230;.. Fazit: Die Mannschaft zeigt derzeit vor allem in der zweiten Halbzeit \u00fcberraschende Fitness und &#8222;Torgeilheit&#8220;. Nachdem die R\u00fcckserie erst schleppend begonnen hat, scheint sich das Team nun gefunden zu haben und es macht Spa\u00df zu sehen, dass man trotz einer komfortablen F\u00fchrung nicht aufh\u00f6rt zu fighten.<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[6,50,1,31],"tags":[],"class_list":["post-5022","post","type-post","status-publish","format-standard","hentry","category-2-herren","category-berichte","category-news","category-senioren-news"],"blocksy_meta":[],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6yR9L-1j0","publishpress_future_action":{"enabled":false,"date":"2026-05-20 12:00:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/5022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/comments?post=5022"}],"version-history":[{"count":3,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/5022\/revisions"}],"predecessor-version":[{"id":5027,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/5022\/revisions\/5027"}],"wp:attachment":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/media?parent=5022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/categories?post=5022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/tags?post=5022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}