{"id":5444,"date":"2012-07-06T14:05:24","date_gmt":"2012-07-06T12:05:24","guid":{"rendered":"http:\/\/rsv-barntrup.de\/Wordpress\/?p=5444"},"modified":"2012-07-06T15:39:50","modified_gmt":"2012-07-06T13:39:50","slug":"gruppeneinteilung-der-bezirksliga-staffel-iii-ist-raus-echte-hammer-dabei","status":"publish","type":"post","link":"https:\/\/rsv-barntrup.de\/Wordpress\/news\/gruppeneinteilung-der-bezirksliga-staffel-iii-ist-raus-echte-hammer-dabei\/","title":{"rendered":"Gruppeneinteilung der Bezirksliga Staffel III ist raus. Echte Hammer dabei&#8230;"},"content":{"rendered":"<p>Am heutigen Tag erschien die Gruppeneinteilung der Bezirksliga-Staffel 3. Darunter sind echte Hammer und die Fahrten zu Ausw\u00e4rtsspielen d\u00fcrften teilweise wohl auch l\u00e4nger werden. Unter anderem ist Augustdorf\u00a0seinem langj\u00e4hrigen und hart umfochtenen Ziel endlich n\u00e4her ger\u00fcckt und kickt nun nicht mehr in der Bielefelder Gruppe. Die Details k\u00f6nnt ihr nachfolgender Aufstellung entnehmen.<\/p>\n<p>Vielen Beteiligten stellt sich die Frage, wo die Lemgoer abgeblieben sind. Lemgo wird mit Leopoldsh\u00f6he so namenhafte Gegner wie R\u00f6dinghausen II, Theesen II \u00a0und Tengern II in der Bezirksligagruppe I\u00a0begr\u00fc\u00dfen d\u00fcrfen. In dieser Gruppe wird es zum Derby mit SC Vlotho kommen. Weiterer Ligakonkurrent ist das Team aus Union Minden.<\/p>\n<p><strong>Bezirksliga Staffel 3 <\/strong><\/p>\n<p>1. <strong>SpVg. Brakel (Absteiger LL 1)<\/strong><\/p>\n<p>2. Blomberger SV (Kreis Detmold)<\/p>\n<p>3. <strong>RSV Barntrup (Absteiger LL 1)<\/strong><\/p>\n<p>4. <strong>T\u00fcrkischer SV Horn ( Aufsteiger Kreis Detmold)<\/strong><\/p>\n<p>5. VfB Beverungen<\/p>\n<p>6. FC Nieheim<\/p>\n<p>7. FC Augustdorf (aus BL2)<\/p>\n<p>8. TuS Horn-Bad Meinberg<\/p>\n<p>9. <strong>FC Stahle (Aufsteiger Kreis H\u00f6xter) <\/strong><\/p>\n<p>10. TuS Erkeln<\/p>\n<p><strong>11. BV Bad Lippspringe (aus BL 4)<\/strong><\/p>\n<p>12. Warburger SF 08<\/p>\n<p>13. SV E. Jerxen-Orbke<\/p>\n<p>14. TuS Bad Driburg<\/p>\n<p><strong>15. SV Menne (Aufsteiger Kreis Warburg) <\/strong><\/p>\n<p><strong>16. SV Marienloh (aus BL 4)<\/strong><\/p>\n<p><strong>17. FC Dahl \/ D\u00f6renhagen 08 (Aufsteiger Kreis Paderborn)<\/strong><\/p>\n<p><strong>18. SV Atteln 21 (aus BL 4)<\/strong><\/p>\n<p>Neben diversen alten Bekannten sind nun auch echte Neulinge der Gruppe zu finden. Besonders die Mannschaft aus Atteln d\u00fcrfte unseren Jungs ein breites Grinsen verpassen. Wir w\u00fcnschen unseren Jungs schon jetzt viel Erfolg in der kommenden Serie. Weghauen..:!!! Nico Haase, altgedienter Kapit\u00e4n der Truppe erkl\u00e4rte bei Radio RSV, dass er sich schon jetzt auf die neuen Gegner freut. Sicher werden viele interessante Partien entstehen und man sieht mal andere Gesichter.<\/p>\n<p>Ersten Ermittlungen und f\u00fcr alle Beteiligten v\u00f6llig \u00fcberraschend sind wir auch in dieser Liga nunmehr das einzige Team, das es schafft einen grundsoliden, immer hervorragenden, wenig staubenden und ordentlich berieselten Ascheplatz aufbieten zu k\u00f6nnen. Der RSV freut sich schon jetzt auf zahlreiche Fans, Anh\u00e4nger und Freunde der gegnerischen Klubs. Sicher werde sich auch langsam einige Sporthistoriker unter das Volk mischen, die mit Bussen anreisen werden. Offensichtlich sind wir langsam aber sicher das letzte gallische Dorf in NRW, dass seine Mannschaften auf einem herrausragenden Ascheplatz antreten lassen muss. M\u00f6glicherweise wird dies aber in Zukunft ein Vorteil sein, denn die letzten Spieler, die aktiv auf einem derartigen Liganiveau\u00a0auf einem Ascheplatz um Punkte rangen sind mittlerweile aussortiert und kicken schon bei den Altherren, wenn \u00fcberhaupt noch&#8230;Vielleicht kommt es bei den gegnerischen Spielern zu einer Art Schockstarre sobald sie unseren Platz sehen. Es wird nachberichtet&#8230;.\u00a0Ascheplatzschuhe wird von denen wohl kaum noch einer kennen&#8230;.. ! In diesem Sinne, f\u00fcr heute habe ich fertig. Allen eine geruhsame Vorbereitung, m\u00f6gen die Trainergeister euch ordentlich schleifen&#8230;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neben diversen alten Bekannten sind nun auch echte Neulinge der Gruppe zu finden. Besonders die Mannschaft aus Atteln d\u00fcrfte unseren Jungs ein breites Grinsen verpassen. Wir w\u00fcnschen unseren Jungs schon jetzt viel Erfolg in der kommenden Serie. Weghauen..:!!! Nico Haase, altgedienter Kapit\u00e4n der Truppe erkl\u00e4rte bei Radio RSV, dass er sich schon jetzt auf die neuen Gegner freut. Sicher werden viele interessante Partien entstehen und man sieht mal andere Gesichter. <\/p>\n<p>Ersten Ermittlungen und f\u00fcr alle Beteiligten v\u00f6llig \u00fcberraschend sind wir auch in dieser Liga nunmehr das einzige Team, das es schafft einen grundsoliden, immer hervorragenden, wenig staubenden und ordentlich berieselten Ascheplatz aufbieten zu k\u00f6nnen. Der RSV freut sich schon jetzt auf zahlreiche Fans, Anh\u00e4nger und Freunde der gegnerischen Klubs. Sicher werde sich auch langsam einige Sporthistoriker<\/p>\n<p>Bezirksliga Staffel 3 <\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[1],"tags":[],"class_list":["post-5444","post","type-post","status-publish","format-standard","hentry","category-news"],"blocksy_meta":[],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6yR9L-1pO","publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:09:20","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/5444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/comments?post=5444"}],"version-history":[{"count":4,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/5444\/revisions"}],"predecessor-version":[{"id":5447,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/5444\/revisions\/5447"}],"wp:attachment":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/media?parent=5444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/categories?post=5444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/tags?post=5444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}