{"id":9095,"date":"2014-08-08T14:15:36","date_gmt":"2014-08-08T12:15:36","guid":{"rendered":"http:\/\/rsv-barntrup.de\/Wordpress\/?p=9095"},"modified":"2014-08-11T03:01:43","modified_gmt":"2014-08-11T01:01:43","slug":"revival-match-am-sporker-holz-22-08-2014-19-00-uhr","status":"publish","type":"post","link":"https:\/\/rsv-barntrup.de\/Wordpress\/news\/revival-match-am-sporker-holz-22-08-2014-19-00-uhr\/","title":{"rendered":"Revival Match am Sporker Holz, 22.08.2014, 19.00 Uhr"},"content":{"rendered":"<p>Jetzt haben se&#8216; zehn Jahre gewartet, um endlich mal zu gewinnen&#8230;..<\/p>\n<p><span style=\"text-decoration: underline;\">Am 22.08.2014, um 19.00 Uhr<\/span>, wollen es die Sporker nochmal wissen. Anl\u00e4sslich des 10-j\u00e4hrigen Jubil\u00e4ums des Bezirksligaaufstiegs gibt es einRevival Match mit den identischen Mannschaften von damals. Wer erinnert sich nicht an die spannenden Spiele auf der Asche.Trotz der damaligen Rivalit\u00e4t wurde nach dem Spiel oft gefeiert. Beide Vereine sind auch heute noch gut befreundet, so dass auch die RSV Kicker auf regen Zuschauerandrang aus Barntrup hoffen. Schlie\u00dflich waren auch die damaligen Partien sehr gut besucht. Also, macht euch auf den Weg gen Spork und unterst\u00fctzt die gute Idee und nat\u00fcrlich die &#8222;alten&#8220; Kicker.<\/p>\n<p>Kommentiert wird das Spiel nat\u00fcrlich ebenfalls; die beiden allseits bekannten Sportkommentatoren Andreas G\u00fcnter\u00a0 Schlingmann sowie Olaf Hohmeier werden dem Publikum ordentlich einheizen.<\/p>\n<p>Um das leibliche Wohl braucht sich selbstverst\u00e4ndlich niemand Sorgen machen. War aber klar!!!<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jetzt haben se&#8216; zehn Jahre gewartet, um endlich mal zu gewinnen&#8230;.. Am 22.08.2014, um 19.00 Uhr, wollen es die Sporker nochmal wissen. Anl\u00e4sslich des 10-j\u00e4hrigen Jubil\u00e4ums des Bezirksligaaufstiegs gibt es einRevival Match mit den identischen Mannschaften von damals. Wer erinnert sich nicht an die spannenden Spiele auf der Asche.Trotz der damaligen Rivalit\u00e4t wurde nach dem Spiel oft gefeiert. Beide Vereine sind auch heute noch gut befreundet, so dass auch die RSV Kicker auf regen Zuschauerandrang aus Barntrup hoffen. Schlie\u00dflich waren auch die damaligen Partien sehr gut besucht. Also, macht euch auf den Weg gen Spork und unterst\u00fctzt die gute Idee und nat\u00fcrlich die &#8222;alten&#8220; Kicker. Kommentiert wird das Spiel nat\u00fcrlich ebenfalls; die beiden allseits bekannten Sportkommentatoren Andreas G\u00fcnter\u00a0 Schlingmann sowie Olaf Hohmeier werden dem Publikum ordentlich einheizen. Um das leibliche Wohl braucht sich selbstverst\u00e4ndlich niemand Sorgen machen. War aber klar!!! &nbsp;<\/p>\n","protected":false},"author":10,"featured_media":9112,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ngg_post_thumbnail":0,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[32,60,1],"tags":[],"class_list":["post-9095","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altliga-news","category-chronik","category-news"],"blocksy_meta":[],"acf":[],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-content\/uploads\/2014\/08\/Spork.bmp","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p6yR9L-2mH","publishpress_future_action":{"enabled":false,"date":"2026-05-20 20:03:47","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/9095","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/comments?post=9095"}],"version-history":[{"count":7,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/9095\/revisions"}],"predecessor-version":[{"id":9104,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/posts\/9095\/revisions\/9104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/media\/9112"}],"wp:attachment":[{"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/media?parent=9095"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/categories?post=9095"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rsv-barntrup.de\/Wordpress\/wp-json\/wp\/v2\/tags?post=9095"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}